{"id":2,"date":"2020-07-15T17:37:59","date_gmt":"2020-07-15T17:37:59","guid":{"rendered":"https:\/\/connect.apsanet.org\/apsa2021\/?page_id=2"},"modified":"2021-10-26T17:51:59","modified_gmt":"2021-10-26T17:51:59","slug":"sample-page","status":"publish","type":"page","link":"https:\/\/connect.apsanet.org\/apsa2021\/","title":{"rendered":"Home"},"content":{"rendered":"<h2>Thank You to our 2021 APSA Annual Meeting &amp; Exhibition Attendees<\/h2>\n<p>We want to thank our attendees, speakers, sponsors, and exhibitors for helping make APSA\u2019s first in-person and virtual annual meeting a success! We hope that you had a productive and overall rewarding experience during the conference. Access to session recordings on the <strong><a href=\"https:\/\/apsa2021.conventus.live\/login\">virtual meeting platform<\/a><\/strong> will be available to registered attendees soon! We appreciate your patience as we work to get all of the recordings uploaded.<\/p>\n<p>APSA is also pleased to offer recordings from the 2021 Annual Meeting for all APSA members as a benefit to the discipline. <b>You can find video highlights <a href=\"https:\/\/apsanet.org\/EVENTS\/Annual-Meeting-Exhibition\/2021-Annual-Meeting-Video-Highlights\">here.<\/a><\/b><\/p>\n<p><strong>We hope to see you all next year for the <a href=\"https:\/\/connect.apsanet.org\/apsa2022\/\">2022 APSA Annual Meeting &amp; Exhibition<\/a>, September 15\u201318, in Montreal, Qu\u00e9bec, Canada!<\/strong><\/p>\n<p>https:\/\/www.youtube.com\/watch?v=hSt4gic_T4Y<\/p>\n<p style=\"text-align: center;\">Thank you from Seattle!<\/p>\n<figure class='gallery-item'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6498576\" data-elementor-lightbox-title=\"Day Three-8October 01, 2021\" href='https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Three-8October-01-2021-1.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Three-8October-01-2021-1-300x200.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Three-8October-01-2021-1-300x200.jpg 300w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Three-8October-01-2021-1-768x513.jpg 768w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Three-8October-01-2021-1-50x33.jpg 50w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Three-8October-01-2021-1-100x67.jpg 100w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Three-8October-01-2021-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\n\t\t\t<\/figure>\n<h3><a href=\"https:\/\/politicalsciencenow.com\/category\/photos-2021\/\">Photo Highlights from the Annual Meeting in Seattle<\/a><\/h3>\n<p>Check out photo highlights from the in-person meeting in Seattle on PSNow. <\/p>\n<figure class='gallery-item'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"53369db\" data-elementor-lightbox-title=\"awards cover\" href='https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/awards-cover-e1634067277845.png'><img decoding=\"async\" width=\"300\" height=\"202\" src=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/awards-cover-e1634067277845-300x202.png\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/awards-cover-e1634067277845-300x202.png 300w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/awards-cover-e1634067277845-1024x691.png 1024w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/awards-cover-e1634067277845-768x518.png 768w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/awards-cover-e1634067277845-50x34.png 50w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/awards-cover-e1634067277845-100x67.png 100w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/awards-cover-e1634067277845.png 1279w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\n\t\t\t<\/figure>\n<h3><a href=\"https:\/\/politicalsciencenow.com\/category\/awards\/\">APSA Award Winners<\/a><\/h3>\n<p>Congratulations to all 2021 APSA Award recipients and thank you to all in-person reception attendees in Seattle!<\/p>\n<figure class='gallery-item'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0788fed\" data-elementor-lightbox-title=\"Day Two-295September 30, 2021\" href='https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Two-295September-30-2021-e1634067733966.jpg'><img decoding=\"async\" width=\"300\" height=\"194\" src=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Two-295September-30-2021-e1634067733966-300x194.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Two-295September-30-2021-e1634067733966-300x194.jpg 300w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Two-295September-30-2021-e1634067733966-768x497.jpg 768w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Two-295September-30-2021-e1634067733966-50x32.jpg 50w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Two-295September-30-2021-e1634067733966-100x65.jpg 100w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/10\/Day-Two-295September-30-2021-e1634067733966.jpg 798w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\n\t\t\t<\/figure>\n<h3 style=\"text-align: center;\" contenteditable=\"true\" data-elementor-setting-key=\"title_text\" data-elementor-inline-editing-toolbar=\"none\" data-pen-placeholder=\"Type Here...\"><strong>Sponsors, Exhibitors &amp; Supporters\u200b<\/strong><\/h3>\n<p style=\"text-align: center;\">Special thanks to all of our 2021 in-person and virtual <strong><a href=\"https:\/\/apsa2021.conventus.live\/sponsors\">sponsors<\/a>, <a href=\"https:\/\/apsa2021.conventus.live\/exhibitors\">exhibitors<\/a><\/strong>, and <strong><a href=\"https:\/\/apsa2021.conventus.live\/sponsors\">supporters<\/a><\/strong>.<\/p>\n<figure class='gallery-item'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3740ab3\" data-elementor-lightbox-title=\"Seattle downtown buildings from Queen Anne hill\" href='https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-1209722729.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-1209722729-300x200.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-1209722729-300x200.jpg 300w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-1209722729-1024x683.jpg 1024w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-1209722729-768x512.jpg 768w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-1209722729-1536x1024.jpg 1536w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-1209722729-2048x1365.jpg 2048w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-1209722729-50x33.jpg 50w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-1209722729-100x67.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\n\t\t\t<\/figure>\n<figure class='gallery-item'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3740ab3\" data-elementor-lightbox-title=\"190830_APSA_297-1024x683\" href='https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2020\/09\/190830_APSA_297-1024x683-1.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2020\/09\/190830_APSA_297-1024x683-1-300x200.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2020\/09\/190830_APSA_297-1024x683-1-300x200.jpg 300w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2020\/09\/190830_APSA_297-1024x683-1-768x512.jpg 768w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2020\/09\/190830_APSA_297-1024x683-1.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\n\t\t\t<\/figure>\n<figure class='gallery-item'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3740ab3\" data-elementor-lightbox-title=\"190830_APSA_297-1024x683\" href='https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-498627705.jpg'><img decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-498627705-300x199.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-498627705-300x199.jpg 300w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-498627705-1024x678.jpg 1024w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-498627705-768x509.jpg 768w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-498627705-1536x1018.jpg 1536w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-498627705-2048x1357.jpg 2048w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-498627705-50x33.jpg 50w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/05\/GettyImages-498627705-100x66.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\n\t\t\t<\/figure>\n<figure class='gallery-item'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3740ab3\" data-elementor-lightbox-title=\"190830_APSA_086-1024x683\" href='https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2020\/09\/190830_APSA_086-1024x683-1.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2020\/09\/190830_APSA_086-1024x683-1-300x200.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2020\/09\/190830_APSA_086-1024x683-1-300x200.jpg 300w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2020\/09\/190830_APSA_086-1024x683-1-768x512.jpg 768w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2020\/09\/190830_APSA_086-1024x683-1.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\n\t\t\t<\/figure>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/bit.ly\/37zgOqZ\"><br \/>\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"320\" src=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/08\/ASN_Website-scaled.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/08\/ASN_Website-scaled.jpg 2560w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/08\/ASN_Website-300x38.jpg 300w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/08\/ASN_Website-1024x128.jpg 1024w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/08\/ASN_Website-768x96.jpg 768w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/08\/ASN_Website-1536x192.jpg 1536w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/08\/ASN_Website-2048x256.jpg 2048w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/08\/ASN_Website-50x6.jpg 50w, https:\/\/connect.apsanet.org\/apsa2021\/wp-content\/uploads\/sites\/68\/2021\/08\/ASN_Website-100x13.jpg 100w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thank You to our 2021 APSA Annual Meeting &amp; Exhibition Attendees We want to thank our attendees, speakers, sponsors, and exhibitors for helping make APSA\u2019s first in-person and virtual annual meeting a success! We hope that you had a productive and overall rewarding experience during the conference. Access to session recordings on the virtual meeting &#8230; <a title=\"Home\" class=\"read-more\" href=\"https:\/\/connect.apsanet.org\/apsa2021\/\" aria-label=\"Read more about Home\">Read more<\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-2","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/connect.apsanet.org\/apsa2021\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/connect.apsanet.org\/apsa2021\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/connect.apsanet.org\/apsa2021\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/connect.apsanet.org\/apsa2021\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/connect.apsanet.org\/apsa2021\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":0,"href":"https:\/\/connect.apsanet.org\/apsa2021\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"wp:attachment":[{"href":"https:\/\/connect.apsanet.org\/apsa2021\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}